{"id":126499,"date":"2016-09-28T11:34:13","date_gmt":"2016-09-28T09:34:13","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/kosova-ne-lufte-me-papunesine\/"},"modified":"2016-10-03T12:44:55","modified_gmt":"2016-10-03T10:44:55","slug":"kosova-ne-lufte-me-papunesine","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/kosova-ne-lufte-me-papunesine\/","title":{"rendered":"Kosova k\u00e4mpft weiterhin mit hoher Arbeitslosigkeit"},"content":{"rendered":"<div dir=\"ltr\">\n<p>Laut offiziellen Angaben liegt die Arbeitslosigkeit in Kosova bei 32.9%. Gewerkschaften sagen aber, die Arbeitslosigkeit liegt viel h\u00f6her &#8211; bei 45%. Eine Verbesserung auf dem Arbeitsmarkt ist laut Wirtschaftsexperten in den kommenden zwei Jahren nicht zu erwarten.<\/p>\n<p>In ihrem letzten Bericht prognostiziert die Weltbank f\u00fcr Kosova einen Wirtschaftswachstum von 3.6%. F\u00fcr das Jahr 2018 sind es immerhin 3.8% vorhergesagt.<\/p>\n<div>Dieses Wirtschaftswachstum zwischen 3% und 4% ist nicht ausreichend, um die Arbeitslosigkeit sp\u00fcrbar zu senken und 25&#8217;000 junge Menschen zu absorbieren, die jedes Jahr\u00a0neu einen Job suchen.<\/div>\n<div><\/div>\n<div>&#8220;Das Wirtschaftswachstum von 3.6% und das j\u00e4hrliche Pro-Kopf-Einkommen von 2&#8217;700 Euro sind vollkommen unzureichend, um die Probleme zu adressieren, mit denen unser Land zu k\u00e4mpfen hat&#8221;, sagt Muhamet Sadiku, Wirtschaftsprofessor. Das Wirtschaftswachstum wird bisher nicht in Verbesserung der Lebenssituation der Menschen in Kosova umgew\u00e4lzt. Damit eine sp\u00fcrbare Verbesserung auf dem Arbeitsmarkt und f\u00fcr das Leben der Menschen kommt, muss Kosova einen j\u00e4hrlichen Wirtschaftswachstum von mindestens 6% erreichen.<\/div>\n<div><\/div>\n<div>&#8220;Die Arbeitslosigkeit kann nur durch die Entwicklung des privaten Sektors erfolgen, durch das produzierende Gewerbe, durch Verbesserung des Businessklimas, durch das Anlocken von ausl\u00e4ndischen Investitionen. Nur so k\u00f6nnen wir j\u00e4hrlich Zehntausende Arbeitslose in den Arbeitsmarkt integrieren&#8221;, so Sadiku.<\/div>\n<div><\/div>\n<div>&#8220;Wir\u00a0brauchen dringend Investitionen und eine Ausweitung\u00a0der eigenen\u00a0Kapazit\u00e4ten. Um die Arbeitslosigkeit zu bek\u00e4mpfen brauchen wir j\u00e4hrlich einen Wirtschaftswachstum von 8%&#8221;. pr\u00e4zisiert Naim Gashi, Wirtschaftsexperte. Der Generator von neuen Arbeitspl\u00e4tzen in den S\u00fcd-Ost-Europ\u00e4ischen L\u00e4ndern\u00a0sei der Privatsektor. Die Hoffnung, dass man die Arbeitslosigkeit durch Investitionen durch grosse internationale Konzerne hat sich f\u00fcr viele Transitionsl\u00e4nder in S\u00fcd-Ost-Europa nicht bewahrheitet.<\/div>\n<div><\/div>\n<div>Das h\u00f6chste Wirtschaftswachstum mit \u00fcber 5% verzeichnete Kosova in den Jahren 2010 und 2011. Von Arbeitslosigkeit sind besonders die Altersgruppen zwischen 15 und 24 Jahren.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Arbeitslosigkeit bleibt weiterhin eines der gr\u00f6ssten Probleme f\u00fcr die Wirtschaft Kosovas. Eine Verbesserung ist bis 2018 nicht zu erwarten.<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-126499","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/126499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=126499"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/126499\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=126499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=126499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=126499"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=126499"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=126499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}