{"id":123352,"date":"2016-08-29T08:24:14","date_gmt":"2016-08-29T06:24:14","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=123352"},"modified":"2016-08-29T08:25:32","modified_gmt":"2016-08-29T06:25:32","slug":"17-jaehriger-wollte-nach-syrien-mit-falscher-identitaet","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/17-jaehriger-wollte-nach-syrien-mit-falscher-identitaet\/","title":{"rendered":"17 J\u00e4hriger wollte nach Syrien mit falscher Identit\u00e4t"},"content":{"rendered":"<div>\n<div>\n<p>Ein 17 J\u00e4hriger aus Gjilan hatte seine Identit\u00e4t gef\u00e4lscht und wollte nach Syrien ausreisen, um sich dem IS in Syrien und Irak anzuschliessen. Doch sein Plan endete am Flughafen Prishtina. Dort wurde er von der kosovarischen Polizei verhaftet.<\/p>\n<p>Der 17 J\u00e4hrige L. Robelli wollte im Februar 2015 nach Syrien ausreisen, berichtet RTK. Doch besorgniserregend ist die Tasache, dass er als Minderj\u00e4hriger sich Reisedokumente mit falscher Identit\u00e4t besorgen konnte. Sein wahrer Nachname ist nicht Robelli, sondern Rexhepi.<\/p>\n<p>Der Vater von Lirim best\u00e4gte, dass der Reisepass und der Ausweis von den lokalen Beh\u00f6rden in der Stadt Gjilan erstellt worden sind.<\/p>\n<\/div>\n<p>Auch wenn er nicht vollj\u00e4hrig ist, ordnete das Gericht an, dass er die Strafe in einem Jugendvollzugsanstalt absitzen muss.<\/p>\n<\/div>\n<p>Laut neuesten Angaben der kosovarischen Polizei hat sich seit September 2015 kein Kosovare sich dem IS angeschlossen. Dies best\u00e4tigte vor Kurzem auch der kosovarische Innenminister, Skender Hyseni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Plan des Minder\u00e4hrigen endete am Flughafen Prishtina &#8220;Adem Jashari&#8221;. Er wurde von der kosovarischen Polizei verhaftet.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-123352","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/123352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=123352"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/123352\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=123352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=123352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=123352"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=123352"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=123352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}