{"id":115734,"date":"2016-06-07T09:47:50","date_gmt":"2016-06-07T07:47:50","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=115734"},"modified":"2016-06-07T09:48:36","modified_gmt":"2016-06-07T07:48:36","slug":"ekr-jahresbericht-2015-rassismusvorfaelle-aus-der-beratungspraxis","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/ekr-jahresbericht-2015-rassismusvorfaelle-aus-der-beratungspraxis\/","title":{"rendered":"EKR &#8211; Jahresbericht 2015: Rassismusvorf\u00e4lle aus der Beratungspraxis"},"content":{"rendered":"<p>Die 239 im Bericht ausgewerteten Vorf\u00e4lle rassistischer Diskriminierung stammen aus den 18 Beratungsstellen aus allen Landesteilen der Schweiz, welche im Beratungsnetz f\u00fcr Rassismusopfer zusammen geschlossen sind. Dem langj\u00e4hrigen Trend entsprechend ist die Arbeitswelt auch im Berichtsjahr 2015 mit 47 Beratungsf\u00e4llen der mit Abstand am st\u00e4rksten betroffene Lebensbereich. Nach der Ausl\u00e4nderfeindlichkeit ist Rassismus gegen Schwarze mit 60 Nennungen das am h\u00e4ufigsten genannte Diskriminierungsmotiv. Danach folgt die Muslimfeindlichkeit, die mit 53 Nennungen im Vergleich zum Vorjahr um 11 Prozent zugenommen hat.<\/p>\n<p>Der Bericht enth\u00e4lt zum einen \u00fcbersichtliche grafische Darstellungen der statistischen Auswertungen aus der Beratungspraxis. Zum anderen wird ein breites Spektrum von anschaulichen Fallbeispielen aufgef\u00fchrt. Der Bericht spiegelt die anhaltend hohe Qualit\u00e4t und die Vielfalt in der Beratungsarbeit der Beratungsstellen wider. Neben allgemeiner Auskunft, psychosozialer Unterst\u00fctzung oder Rechtsberatung f\u00fcr die betroffene Person leisten die Beratungsstellen auch einen wichtigen Beitrag zur Konfliktbew\u00e4ltigung. Ausserdem leiten die Beratungsstellen ratsuchende Personen bei Bedarf auch an andere Fachstellen, spezialisierte Anwaltskanzleien, psychologische oder medizinische Experten wie auch an die Polizei weiter.<\/p>\n<p>Die F\u00e4lle aus der Beratungspraxis der Beratungsstellen in der Schweiz wurden vom Verein humanrights.ch zusammengetragen und gemeinsam mit der Eidgen\u00f6ssischen Kommission gegen Rassismus EKR ausgewertet. Der Bericht 2015 erscheint in einem neuen Format und mit leicht angepassten Kategorien, welche jedoch die Vergleichbarkeit mit fr\u00fcheren Analysen erlauben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die meisten gemeldeten Diskriminierungsf\u00e4lle finden in der Arbeitswelt statt. Dies zeigt der Bericht des Beratungsnetzes f\u00fcr Rassismusopfer f\u00fcr das Jahr 2015. Die h\u00e4ufigsten Formen der Diskriminierung waren Beschimpfungen, herabw\u00fcrdigende Behandlungen und Benachteiligungen. Das h\u00e4ufigste Tatmotiv war die Ausl\u00e4nderfeindlichkeit, gefolgt vom Rassismus gegen Schwarze. Zugenommen haben F\u00e4lle von Muslimfeindlichkeit.<\/p>\n","protected":false},"author":10,"featured_media":115731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-115734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/115734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=115734"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/115734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/115731"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=115734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=115734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=115734"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=115734"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=115734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}