{"id":112635,"date":"2016-05-02T09:26:21","date_gmt":"2016-05-02T07:26:21","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=112635"},"modified":"2016-05-02T09:26:50","modified_gmt":"2016-05-02T07:26:50","slug":"azem-syla-stellt-sich","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/azem-syla-stellt-sich\/","title":{"rendered":"Azem Syla stellt sich"},"content":{"rendered":"<p>Dem Abgeordneten im kosovarischen Parlement, Azem Syla (geh\u00f6rt der regierenden PDK) wird organisierte Kriminalit\u00e4t und Geldw\u00e4sche vorgeworfen.<\/p>\n<p>Nachdem er einige aus der \u00d6ffentlichkeit verschwand, stellte sich Azem Syla am Freitag 11 Uhr der Polizei in der Hauptstadt Prishtina.<\/p>\n<p>Er wurde von der Grenzpolizei begleitet. Syla wird organisierte Kriminalit\u00e4t und Geldw\u00e4sche vorgeworfen. Der Anwalt Tom\u00eb Gashi best\u00e4tigte die Informationen, dass Azem Syla sich in Kosova befindet.<\/p>\n<p>&#8220;Er ist hier. Wir warten darauf, zu erfahren, wo er hingebracht wird. Vielleicht ist er bei der Staatsanwaltschaft, denn ein Haftbefehl habe ich bisher noch nicht gesehen&#8221;, zitiert KTV den Anwalt Gashi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dem Abgeordneten im kosovarischen Parlement, Azem Syla (geh\u00f6rt der regierenden PDK) wird organisierte Kriminalit\u00e4t und Geldw\u00e4sche vorgeworfen. Nachdem er einige aus der \u00d6ffentlichkeit verschwand, stellte sich Azem Syla am Freitag 11 Uhr der Polizei in der Hauptstadt Prishtina. Er wurde von der Grenzpolizei begleitet. Syla wird organisierte Kriminalit\u00e4t und Geldw\u00e4sche vorgeworfen. Der Anwalt Tom\u00eb Gashi [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-112635","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/112635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=112635"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/112635\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=112635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=112635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=112635"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=112635"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=112635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}