{"id":110950,"date":"2016-04-12T09:47:55","date_gmt":"2016-04-12T07:47:55","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=110950"},"modified":"2016-04-12T09:55:34","modified_gmt":"2016-04-12T07:55:34","slug":"niedrige-loehne-rund-700-aerzte-haben-mazedonien-verlassen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/niedrige-loehne-rund-700-aerzte-haben-mazedonien-verlassen\/","title":{"rendered":"Niedrige L\u00f6hne, rund 700 \u00c4rzte haben Mazedonien verlassen"},"content":{"rendered":"<div>\n<p>Weil sie mit der Entlohnung und den Arbeitsbedingungen in Mazedonien unzufrieden sind, haben rund 700 \u00c4rzte dem Land den R\u00fccken gekehrt. Sie sind nach Europa auf der Suche nach einen besseren Leben mit besseren Standards ausgewandert, sagte der Chef der \u00c4rztegewerkschaft in Mazedonien Simon Siljanovski. Es bestehe die Gefahr, dass dieser negative Trend weiterhin anh\u00e4lt.<\/p>\n<\/div>\n<div>\n<p>&#8220;Sicherlich f\u00fchlen sie sich von den besseren Arbeitsbedingungen in Ausland angelockt. Hinzu kommt, dass die Entlohung in Europa viel besser ist als in Mazedonien. In Norwegen beispielweilse erhalten die \u00c4rzte pro Tag, das was sie in Mazedonien pro Monat erhalten w\u00fcrden&#8221;, betont Siljanovski.<\/p>\n<\/div>\n<div>\n<p>Es besteht grosse Gefahr, dass man die Spezialisten, die bald in Rente gehen, nicht mehr ersetzt werden k\u00f6nnen, so Siljanovski. Er fordert von den Insitutionen des Landes, dringende Massnahmen zu ergreifen.<\/p>\n<\/div>\n<div>\n<p>&#8220;Von insgesamt 2000 Spezialisten sind 70% vor der Pensionierung. Diese Situation ist alarmierend&#8221;, sagt Siljanovski.<\/p>\n<\/div>\n<div>Die Auwanderung der \u00c4rzte ist in allen St\u00e4dten Mazedoniens zu sp\u00fcren, auch in den mehrheitlich von Albanern bewohnten St\u00e4dten.<\/div>\n<div>Asim Musa, Direktor des Dialysespitals in Struga, sieht ebenfalls die niedrigen L\u00f6hne und die schlechten Arbeitsbedingungen als Gr\u00fcnde f\u00fcr die alarmierende Auswanderung der \u00c4rzte aus Mazedonien, schreibt AlsatM, berichtet <a href=\"http:\/\/albinfo.ch\/\" target=\"_blank\">albinfo.ch<\/a>. In Struga und in Ohrid ist das Fehlen der \u00c4rzte in mehreren Abteilungen bereits zu sp\u00fcren, so Musa.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die niedrigen L\u00f6hne haben viele \u00c4rzte dazu gezwungen, Mazedonien zu verlassen. Die Auswanderung von rund 700 \u00c4rzten hat eine grosse L\u00fccke hinterlassen, sagen die Gewerkschaften.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-110950","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/110950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=110950"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/110950\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=110950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=110950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=110950"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=110950"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=110950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}