{"id":108901,"date":"2016-03-18T10:07:09","date_gmt":"2016-03-18T09:07:09","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=108901"},"modified":"2016-03-18T10:07:09","modified_gmt":"2016-03-18T09:07:09","slug":"polizei-jagt-aktivisten-von-vetevendosje","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/polizei-jagt-aktivisten-von-vetevendosje\/","title":{"rendered":"Polizei jagt Aktivisten von Vet\u00ebvendosje"},"content":{"rendered":"<p>Die kosovarische Polizei verfolgt die Aktivisten der gr\u00f6ssten oppositionellen Partei Vet\u00ebvendosje. Mehrere Aktivisten sind verhaftet und einige stehen vor Gericht. Donnerstag Morgen wurde der Direktor des Inspektorats der Hauptstadt Prishtina, Xhelal Svecla, verhaftet. Auch der Sekret\u00e4r f\u00fcr internationale Beziehungen der Bewegung Vet\u00ebvendosje, Boiken Abazi, wurde verhaftet und des Landes verwiesen.<\/p>\n<p>Im Laufe des gestrigen Tages standen mehrere Aktivisten von Vet\u00ebvendosje vor Gericht gebracht, unter anderem der Sekret\u00e4r f\u00fcr Organisation, Dardan Molliqaj, der Chef der Fraktion von Vet\u00ebvendosje im kosovarischen Parlament, Glauk Konjufca und der Aktivist Frash\u00ebr Krasniqi. Alle drei stehen nicht mehr im Hausarrest.<\/p>\n<p>F\u00fcr die Bewegung Vet\u00ebvendosje sind diese Verhaftungen politisch motiviert und von der Regierung dirigiert. &#8220;Diese kriminelle Regierung will um jeden Preis den Wiederstand brechen, damit sie die Projekte Serbiens in Kosova umsetzen und Montenegro unser Land schenken kann.&#8221;<\/p>\n<p>Der kosovarischen Staatsanwaltschaft liegen 80 Dossiers vor, in denen es um Korruptionsaff\u00e4ren des ehemaligen B\u00fcrgermeisters von Prishtina, Isa Mustafa, geht. Stattdessen besch\u00e4ftigt sich die Staatsanwaltschaft aber mit der oppositionellen Vet\u00ebvendosje. &#8220;Die Verhaftung von Svecla ist ein Versuch, seine Arbeit zu behindern, damit die organisierte Kriminalit\u00e4t, die von den Exponenten von LDK und PDK gef\u00fchrt wird, wieder offene T\u00fcren hat&#8221;, heisst es in einer Mitteilung von Vet\u00ebvendosje.<\/p>\n<p>&#8220;Die Verhaftung von Boiken Abazi, die einem Kidnapping \u00e4hnelt, ist ein koordinierter Feldzug der Regierung, um Angst und Terror zu verbreiten &#8211; besonders bei den Aktivisten von Vet\u00ebvendosje. Die Regierung will, dass die gr\u00f6sste oppositionelle Partei ihre Aktivit\u00e4ten einstelt. Die Polizei ist wieder zu einem Mittel des Regimes geworden.&#8221;<\/p>\n<p>Boiken Abazi wurde von der Polizei bis zur kosovarisch-albanischen Grenze begleitet und des Landes verwiesen. &#8220;Die Polizei hat ihm nicht mal erm\u00f6glicht, seine pers\u00f6nlichen Sachen und Dokumente mitzunehmen. Er wurde als eine gef\u00e4hrliche Person eingestuft, auch wenn dies niergends festgehalten worden ist&#8221;.<\/p>\n<p>Unterdessen sind Dardan Molliqaj, Glauk Konjufca und Frash\u00ebr Krasniqi wieder frei. Sie wurden verhaftet im Bezug auf eine Aktion von Vet\u00ebvendosje im Jahr 2009. Damals hatten Aktivisten von Vet\u00ebvendosje als eine Protestaktion Autos von der EULEX-Mission umgekippt. Auch Xhelal Svecla wurde wegen dieses Falles, der nun 7 Jahre zur\u00fcckliegt, verhaftet.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kosovo-Polizei hat gestern morgen den Direktor des Inspektorats der Hauptstadt Prishtina, Xhelal Svecla, verhaftet. Boiken Abazi wurde ebenfalls verhaftet und des Landes verwiesen.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-108901","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/108901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=108901"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/108901\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=108901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=108901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=108901"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=108901"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=108901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}