{"id":106444,"date":"2016-02-19T09:25:13","date_gmt":"2016-02-19T08:25:13","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=106444"},"modified":"2016-02-19T09:27:15","modified_gmt":"2016-02-19T08:27:15","slug":"httpwww-albinfo-chwp-adminpost-new-phplangdepost_typeposttrid35977source_langsq","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/httpwww-albinfo-chwp-adminpost-new-phplangdepost_typeposttrid35977source_langsq\/","title":{"rendered":"Opposition stellt Regierung Ultimatum: In 10 Tagen R\u00fccktritt oder weitere Demonstrantionen"},"content":{"rendered":"<p>Die oppositionellen Parteien habe der kosovarischen Regierung ein Ultimatum gestellt. Bis zum 27. Februar soll sie zur\u00fccktreten, sonst werden die Masenproteste weitergehen.<\/p>\n<p>Die Opposition hat der kosovarischen Regierung ein Ultimatum gestellt. Sie soll in 10 Tagen zur\u00fccktreten und Neuwahlen ausschreiben, sonst werden die Massenproteste weitergehen. Dies war die Hauptforderung der Demonstration der Opposition in Prishtina am vergangenen Dienstag. Zehntausende protestierten gegen die Regierung.<\/p>\n<p>Die letzte Demonstration verlief ohne einen einzigen Zwischenfall und ohne Ausseinandersetzungen mit den Sicherheitskr\u00e4ften, anders als die vergangenen Demonstrationen der Opposition. Die Oppositionsf\u00fchrer sagten, die Neuwahlen sind der einzige Ausweg aus der parlamentarischen Krise. Andernfalls werden die Proteste weitergehen.<\/p>\n<p>Regierungschef Isa Mustafa und Vize-Regierungschef Hashim Thaci reagierten umgehend. Die n\u00e4chsten Wahlen werden im Juni 2018 stattfinden, so wie sie im Gesetz auch vorgesehen sind. Sie dankten den Mitb\u00fcrgern f\u00fcr den ruhigen und friedlichen Protest. Das Ultimatum der Opposition lehnten sie aber ab.<\/p>\n<p>Der Vorsitzende der oppositionellen Bewegung Vet\u00ebvendosje! Visar Ymeri, sagte, die Regierung habe bis zum 27. Februar Zeit, um zur\u00fcckzutreten. Neuwahlen m\u00fcssen umgehend ausgerufen werden. Wenn dies nicht geschieht werden die Proteste weitergehen. Wenn die Regierung geht, dann wird die Republik gerettet und sie wird \u00fcberleben. Die beiden sehr umstrittenen und f\u00fcr Kosova sch\u00e4dlichen Abkommen mit Serbien und Montenegro werden nicht durchgehen. Die Demonstration sei eine Manifestation f\u00fcr Gerechtigkleit, denn diese Regierung &#8220;ist eine Regierung, bei der einige M\u00e4chtige \u00fcber Nacht reich werden&#8221;. &#8220;Wenn die Neuwahlen nicht bis zum 27. Februar ausgeschrieben werden, werden wir unsere Demonstrationen weiterf\u00fchren&#8221;, sagte Ymeri.<\/p>\n<p>Nur die B\u00fcrger k\u00f6nnen entscheiden und diese Regierung st\u00fcrzen, sagte Rramush Haradinaj, der Chef der AAK. Die Regierung hat die Souverenit\u00e4t und die territoriale Integrit\u00e4t und die Verfassung des Langes angegriffen und mit F\u00fcssen getreten.<\/p>\n<p>&#8220;Heute hat das kosovarische Volk dieser Regierung die Legitimit\u00e4t entzogen. Darum m\u00fcssen Neuwahlen her, damit die B\u00fcrger entscheiden k\u00f6nnen, wer das Land k\u00fcnftig regieren soll&#8221;, sagte in seiner Ansprache Fatmir Limaj von NISMA.<\/p>\n<p>Premierrminister Isa Mustafa und sein Stellvertreter Hashim Thaci hielten gleich nach dem Ende des Protestes eine Medienkonferenz. In einer drohenden Sprache sagte Thaci, man h\u00e4tte darauf gewartet, dass die Oppositionellen kommen. und man h\u00e4tte sie nicht Kaffe servieren wollen, sondern f\u00fcr sie die verdiente Antwort parat gehabt. Doch die Opposition sei nicht gekommen, sie h\u00e4tte den Schwanz eingezogen. Thaci Dankte den Menschen, die sich nicht der Opposition angeschlossen haben. Ob der mit dieser Wortwahl die Opposition provoziert, wollten Medienvertreter wissen. &#8220;Nein, keineswegs&#8221;, sagte Thaci. &#8220;Wir haben sie zum Dialog eingeladen&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die oppositionellen Parteien habe der kosovarischen Regierung ein Ultimatum gestellt. Bis zum 27. Februar soll sie zur\u00fccktreten, sonst werden die Masenproteste weitergehen. Die Opposition hat der kosovarischen Regierung ein Ultimatum gestellt. Sie soll in 10 Tagen zur\u00fccktreten und Neuwahlen ausschreiben, sonst werden die Massenproteste weitergehen. Dies war die Hauptforderung der Demonstration der Opposition in Prishtina [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-106444","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/106444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=106444"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/106444\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=106444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=106444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=106444"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=106444"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=106444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}