{"id":104655,"date":"2016-01-29T10:59:59","date_gmt":"2016-01-29T09:59:59","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=104655"},"modified":"2016-01-29T10:59:59","modified_gmt":"2016-01-29T09:59:59","slug":"usa-unterstuetzen-fsk-mit-9-2-millionen-dollar","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/usa-unterstuetzen-fsk-mit-9-2-millionen-dollar\/","title":{"rendered":"USA unterst\u00fctzen FSK mit 9.2 Millionen Dollar"},"content":{"rendered":"<p>F\u00fcr das Jahr 2016 hat die US-Regierung der FSK finanzielle Unterst\u00fctzung in H\u00f6he von 9.2 Millionen Dollar zugesagt. Die Gelder sollen haupts\u00e4chlich\u00a0f\u00fcr die Modernisierung der Kommunikationstechnoligie der\u00a0operativen Einheiten der FSK verwendet werden.<\/p>\n<div>Das Abkommen wurde im Rahmen der bilateralen Zusammenarbeit mit der US-Botschaft in Prishtina unterzeichnet. Im Namen der USA unterzeichnete Oberst David Bennet und im Namen der kosovarischen Regierung Shk\u00eblzen Syla.<\/div>\n<div><\/div>\n<div>Neben der Modernisierung der Kommunikationstechnologie sollen die finanziellen Mittel auch in die Aus- und Weiterbildung der Mitglieder der FSK fliessen.<\/div>\n<div><\/div>\n<div>Dank der Unterst\u00fctzung durch die US-Regierung kann die Kosovo Security Force ihre\u00a0operationelle\u00a0\u00a0<wbr \/>Kapazit\u00e4ten steigern und die Spezialisierung ihrer Mitglieder kontinuierlich vorantreiben.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die USA unterst\u00fctzen die Kosovo Security Force (FSK) mit 9.2 Millionen Dollar<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-104655","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/104655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=104655"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/104655\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=104655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=104655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=104655"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=104655"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=104655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}