{"id":104651,"date":"2016-01-29T10:35:15","date_gmt":"2016-01-29T09:35:15","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=104651"},"modified":"2016-01-29T10:37:50","modified_gmt":"2016-01-29T09:37:50","slug":"niederlage-fuer-kosova-im-europarat","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/niederlage-fuer-kosova-im-europarat\/","title":{"rendered":"Niederlage f\u00fcr Kosova im Europarat"},"content":{"rendered":"<p>Nach der Niederlage bez\u00fcglich der Mitgliedschaft bei der UNESCO hat Kosova nun eine weitere Niederlage auf dem diplomatischen Parkett hinnehmen m\u00fcssen. Der Europarat verabschiedete eine Resolution, die vier von Serbien vorgeschlagene \u00c4nderungsantr\u00e4ge beinhaltet.<\/p>\n<p>Die Resolution handelt vom Abkommen zwischen Kosova und Serbien bez\u00fcglich der Gr\u00fcndung des Bundes der Gemeinden mit serbischer Mehrheit, f\u00fcr den Schutz der serbischen Kulturerbe in Kosova (auch wenn Kosova wegen der serbischen Blockade nicht UNESCO-Mitglied werde konnte) und f\u00fcr die \u00dcbertragung von Kompetenzen auf die UNMIK-Mission in Bezug auf Organisationen wie Interpol und Europol.<\/p>\n<p>Auch wenn die serbischen \u00c4nderungsantr\u00e4ge von der albanischen Delegation abgelehnt wurden &#8211; unterst\u00fctzt von Grossbritanien, von der T\u00fcrkei, Ungarn und Schweden, wurden sie am Ende doch verabschiedet.<\/p>\n<p>Die albanischen Vertreter brachten ihre Antr\u00e4ge ein, die die serbischen Antr\u00e4ge zu Fall bringen sollten, doch sie wurden nicht angenommen. Auch die schwedische Delegation brachte einige \u00c4nderungsantr\u00e4ge, doch am Ende konnte sich die serbische Delegation durchsetzen. Es fehlte nur eine Stimme &#8211; die albanische Vertreterin aus Mazedonien Ermira Mehmeti fehlte bei der wichtigen Abstimmung.<\/p>\n<p>Der Resolutionsentwurf wurde vom spanischen Abgeordneten Agustin Conde verfasst. Der urspr\u00fcngliche Entwurf bewertete positiv die demokratische Entwicklung von Kosova und die St\u00e4rkung des Rechtsstaates. Im Kern ging es um den Vorschlag zur Vertiefung des Dialogs zwischen der parlamentarischen Versammlung des Europarates und des kosovarischen Parlamentes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Resolution f\u00fcr Kosova im Europarat wurde am Donnerstag verabschiedet. Es beinhaltet vier von Serbien vorgeschlagene \u00c4nderungsantr\u00e4ge<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-104651","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/104651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=104651"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/104651\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=104651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=104651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=104651"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=104651"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=104651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}