{"id":102450,"date":"2016-01-06T09:57:57","date_gmt":"2016-01-06T08:57:57","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=102450"},"modified":"2016-01-08T09:26:15","modified_gmt":"2016-01-08T08:26:15","slug":"kosova-hat-hochste-arbeitslosigkeit-in-der-region","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/kosova-hat-hochste-arbeitslosigkeit-in-der-region\/","title":{"rendered":"Kosova hat h\u00f6chste Arbeitslosigkeit in der Region"},"content":{"rendered":"<div><\/div>\n<div class=\"yj6qo ajU\">\n<div id=\":yv\" class=\"ajR\" tabindex=\"0\" data-tooltip=\"Afficher le contenu abr\u00e9g\u00e9\">\n<p><img decoding=\"async\" class=\"ajT\" src=\"https:\/\/ssl.gstatic.com\/ui\/v1\/icons\/mail\/images\/cleardot.gif\" alt=\"\" \/>Auch wenn es im Jahr 2015 eine positive Entwicklung gab, liegt Kosova bez\u00fcglich der Anzahl der Besch\u00e4ftigten auf dem letzten Platz in der Region. In den Jahren 2012-2013 gab es einen leichten R\u00fcckgang der Arbeitslosigkeit (von 30.9% auf 30%), doch im Jahr 2014 stiegt die Arbeitslosenquote auf 35%.<\/p>\n<p>&#8220;Wir haben die neuen Zahlen f\u00fcr das Jahr 2015, doch wir k\u00f6nnen sie immer noch nicht ver\u00f6ffentlichen. Ich kann nur best\u00e4tigen, dass wir im vergagenen Jahr eine positive Entwicklung verzeichnet haben&#8221;, sagte der Direktor der Abteilung f\u00fcr Sozialen Statistiken beim kosovarischen Statistikamt, Bashkim Bellaqa.<\/p>\n<p>&#8220;In Kosova ist die Arbeitslosigkeit besonders bei den 15 bis 24 J\u00e4hrigen sehr hoch &#8211; sie liegt bei 61%. Desweiteren haben 71.6% der Besch\u00e4ftigten nur eine befreistete Stelle&#8221;, so Bellaqa.<\/p>\n<p>Mit diesen Statistiken bleibt Kosova weiterehin an der Spitze der L\u00e4nder in der Region. Danach kommen Bosnien und Herzegovina mit 27.5% und Serbien mit 18.9%.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In Kosova liegt die Arbeitslosenquote bei den 15 bis 24 J\u00e4hrigen bei 61%.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-102450","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/102450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=102450"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/102450\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=102450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=102450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=102450"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=102450"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=102450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}